{"id":14169,"date":"2022-03-02T14:09:43","date_gmt":"2022-03-02T14:09:43","guid":{"rendered":"http:\/\/www.maisonq8.com\/?post_type=product&#038;p=14169"},"modified":"2023-12-18T11:41:33","modified_gmt":"2023-12-18T11:41:33","slug":"calvin-klein-ck-shock-200ml-eau-de-toilette-for-men","status":"publish","type":"product","link":"https:\/\/www.maisonq8.com\/ar\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/","title":{"rendered":"Calvin Klein CK Shock 200ml Eau de Toilette for Men<span class=\"codevz-product-category-after-title\">\u0645\u064a\u0632\u0648\u0646 \u0623\u0648\u062a\u0644\u062a<\/span>"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><b>CK One Shock For Him<\/b>\u00a0is built around aromatic, spicy and deep &#8230; <\/p>","protected":false},"featured_media":14170,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[932,988],"product_tag":[],"class_list":["post-14169","product","type-product","status-publish","has-post-thumbnail","product_cat-brand-for-less","product_cat-perfume-brand-for-less","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calvin Klein CK Shock 200ml Eau de Toilette for Men - MaisonQ8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maisonq8.com\/ar\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calvin Klein CK Shock 200ml Eau de Toilette for Men - MaisonQ8\" \/>\n<meta property=\"og:description\" content=\"CK One Shock For Him\u00a0is built around aromatic, spicy and deep ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maisonq8.com\/ar\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/\" \/>\n<meta property=\"og:site_name\" content=\"MaisonQ8\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-18T11:41:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maisonq8.com\/wp-content\/uploads\/2022\/03\/29-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/product\\\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\\\/\",\"url\":\"https:\\\/\\\/www.maisonq8.com\\\/product\\\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\\\/\",\"name\":\"Calvin Klein CK Shock 200ml Eau de Toilette for Men - MaisonQ8\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/product\\\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/product\\\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maisonq8.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/29-scaled.jpg\",\"datePublished\":\"2022-03-02T14:09:43+00:00\",\"dateModified\":\"2023-12-18T11:41:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/product\\\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.maisonq8.com\\\/product\\\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/product\\\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.maisonq8.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/29-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.maisonq8.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/29-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/product\\\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.maisonq8.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.maisonq8.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Calvin Klein CK Shock 200ml Eau de Toilette for Men\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/#website\",\"url\":\"https:\\\/\\\/www.maisonq8.com\\\/\",\"name\":\"\u0628\u064a\u062a \u0627\u0644\u0639\u0637\u0631\",\"description\":\"Perfumes &amp; More\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.maisonq8.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/#organization\",\"name\":\"Maison Q8\",\"url\":\"https:\\\/\\\/www.maisonq8.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.maisonq8.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Brand-logo-PERFUME1-1920x1200-1.jpg\",\"contentUrl\":\"http:\\\/\\\/www.maisonq8.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Brand-logo-PERFUME1-1920x1200-1.jpg\",\"width\":1920,\"height\":1200,\"caption\":\"Maison Q8\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maisonq8.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calvin Klein CK Shock 200ml Eau de Toilette for Men - MaisonQ8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maisonq8.com\/ar\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/","og_locale":"ar_AR","og_type":"article","og_title":"Calvin Klein CK Shock 200ml Eau de Toilette for Men - MaisonQ8","og_description":"CK One Shock For Him\u00a0is built around aromatic, spicy and deep ...","og_url":"https:\/\/www.maisonq8.com\/ar\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/","og_site_name":"MaisonQ8","article_modified_time":"2023-12-18T11:41:33+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/www.maisonq8.com\/wp-content\/uploads\/2022\/03\/29-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maisonq8.com\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/","url":"https:\/\/www.maisonq8.com\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/","name":"Calvin Klein CK Shock 200ml Eau de Toilette for Men - MaisonQ8","isPartOf":{"@id":"https:\/\/www.maisonq8.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maisonq8.com\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/#primaryimage"},"image":{"@id":"https:\/\/www.maisonq8.com\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maisonq8.com\/wp-content\/uploads\/2022\/03\/29-scaled.jpg","datePublished":"2022-03-02T14:09:43+00:00","dateModified":"2023-12-18T11:41:33+00:00","breadcrumb":{"@id":"https:\/\/www.maisonq8.com\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maisonq8.com\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.maisonq8.com\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/#primaryimage","url":"https:\/\/www.maisonq8.com\/wp-content\/uploads\/2022\/03\/29-scaled.jpg","contentUrl":"https:\/\/www.maisonq8.com\/wp-content\/uploads\/2022\/03\/29-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.maisonq8.com\/product\/calvin-klein-ck-shock-200ml-eau-de-toilette-for-men\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.maisonq8.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.maisonq8.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Calvin Klein CK Shock 200ml Eau de Toilette for Men"}]},{"@type":"WebSite","@id":"https:\/\/www.maisonq8.com\/#website","url":"https:\/\/www.maisonq8.com\/","name":"\u0628\u064a\u062a \u0627\u0644\u0639\u0637\u0631","description":"Perfumes &amp; More","publisher":{"@id":"https:\/\/www.maisonq8.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maisonq8.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.maisonq8.com\/#organization","name":"Maison Q8","url":"https:\/\/www.maisonq8.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.maisonq8.com\/#\/schema\/logo\/image\/","url":"http:\/\/www.maisonq8.com\/wp-content\/uploads\/2022\/12\/Brand-logo-PERFUME1-1920x1200-1.jpg","contentUrl":"http:\/\/www.maisonq8.com\/wp-content\/uploads\/2022\/12\/Brand-logo-PERFUME1-1920x1200-1.jpg","width":1920,"height":1200,"caption":"Maison Q8"},"image":{"@id":"https:\/\/www.maisonq8.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/product\/14169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/comments?post=14169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/media\/14170"}],"wp:attachment":[{"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/media?parent=14169"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/product_brand?post=14169"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/product_cat?post=14169"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.maisonq8.com\/ar\/wp-json\/wp\/v2\/product_tag?post=14169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}